{"id":13205,"date":"2022-07-01T11:24:18","date_gmt":"2022-07-01T07:24:18","guid":{"rendered":"https:\/\/aixgroup.ch\/?p=13205"},"modified":"2022-07-01T11:24:18","modified_gmt":"2022-07-01T07:24:18","slug":"a-quarter-of-successful-deliverables","status":"publish","type":"post","link":"https:\/\/aixgroup.ch\/it\/a-quarter-of-successful-deliverables\/","title":{"rendered":"Un Quarto di Risultati Positivi"},"content":{"rendered":"<p><strong>Messaggio de Presidente del Consiglio<\/strong><\/p>\n<p><em>&#8220;Abbiamo grandi piani per elevare la crescita del business e abbiamo immaginato un grande futuro, per i nostri clienti e l&#8217;azienda&#8221;<\/em><\/p>\n<p>Un quarto di risultati positivi<\/p>\n<p>Sostenendo l&#8217;ottimo inizio dell&#8217;anno per tutto il secondo trimestre, ci siamo concentrati sul conseguimento di risultati positivi nonostante un cambiamento nel mercato. Il nostro piano strategico del business, combinato con i nostri prodotti innovativi, ci ha aiutato a superare il mercato turbolento, attirando nuovi investitori e aumentando il flusso netto positivo nel business.<\/p>\n<p>Alla luce del mantenimento di un ottimo rapporto con i nostri partner, RC Celta ci ha visitato per tre giorni alla presenza di importanti membri del team e della direzione. Le discussioni includevano la strategia futura e lo sviluppo del partenariato. Continuiamo a sostenere le nostre associazioni con altri partner allo stesso modo e abbiamo piani aggiuntivi con loro nel corso dell&#8217;anno.<\/p>\n<p>Guidando il successo alle nostre attivit\u00e0 ed ai nostri dipendenti, abbiamo portato avanti la nostra visione di far avanzare ulteriormente il nostro team sul fronte degli investimenti, rafforzandoli attraverso l&#8217;istruzione. Poich\u00e9 crediamo fermamente che investire nel capitale umano sia essenziale per la crescita organizzativa, abbiamo organizzato, in coalizione con la rinomata Scuola del Business di Harvard, un corso di formazione certificato sugli Investimenti Alternativi, che ci ha permesso una grande vittoria sul mercato.<br \/>\nConcentrandosi sulle tendenze del mercato, la tecnologia blockchain \u00e8 sempre alta. Ci sono ancora molte caselle deselezionate e punti interrogativi, ma senza alcun dubbio, con una corretta implementazione e linee guida adeguate, la tecnologia ha il potenziale per rivoluzionare il panorama economico su scala globale. Come qualsiasi Tecnologia per Uso Generale &#8211; GPT, ci vuole tempo per adottare e adattarsi. Gli NFT (token non fungibili) stanno decollando a un ritmo veloce, gli investimenti ESG (Ambientale, Sociale e di Governance) stanno lasciando un grande segno nel settore, l&#8217;Intelligenza Artificiale ha tutte le possibilit\u00e0 di diventare l&#8217;industria pi\u00f9 influente del secolo e il Metaverso potrebbe essere la prossima grande opportunit\u00e0 di investimento. \u00c8 davvero sicuro dire aspettarsi l&#8217;inaspettato.<\/p>\n<p>Infine, sono lieto di condividere con voi che il mese scorso il Gruppo AIX per gli Investimenti \u00e8 stato orgoglioso di ricevere un altro premio, \u201cl&#8217;International Investor Award\u201d per la migliore societ\u00e0 di consulenza sugli investimenti per la regione MENA, 2022.<\/p>\n<p>Mentre ci spostiamo alla seconda met\u00e0 dell&#8217;anno, abbiamo grandi piani per elevare la crescita del business e abbiamo immaginato un grande futuro, per i nostri clienti e l&#8217;azienda.<\/p>\n<p><strong>Piano 144 &#8211; Un nuovo ufficio con vista su Dubai<\/strong><\/p>\n<p>Con la crescita dell&#8217;azienda, per migliorare la sua funzionalit\u00e0 e ospitare il personale in crescita del il Gruppo AIX per gli Investimenti, \u00e8 stato aggiunto un nuovo piano al suo ufficio a Dubai. Lo spazio dell\u2019ufficio si estende sul 144 piano del Burj Khalifa, caratterizzato da interni minimalisti eleganti disegnato da un eminente studio di design negli Emirati Arabi Uniti. La vista dalle finestre dal pavimento al soffitto e dalle aree spaziose \u00e8 mozzafiato. L&#8217;ufficio comprende un raro attributo dei piani alti del Burj Khalifa, un ampio balcone con vista sulla bellissima citt\u00e0 di Dubai.<\/p>\n<p><strong>Jersey rivelata dalla cima del mondo<\/strong><\/p>\n<p>L&#8217;RC Celta ha svelato la sua seconda maglia per la prossima stagione presso l&#8217;ufficio del Gruppo AIX per gli Investimenti a Dubai. A tema con la loro ultima campagna, &#8220;Back to Black&#8221;, stanno tornando ancora una volta su una maglia nera. I giocatori della squadra hanno sfoggiato una maglia simile nella stagione 2017\/2018. Presenta nuove attraenti interpretazioni in oro e, tra gli altri sponsor, il logo del Gruppo AIX per gli Investimenti \u00e8 in oro sulla manica sinistra.<\/p>\n<p><strong>Approfondimenti Blockchain &#8211; Trasformazione e gioco, Reda Bouraoui<\/strong><\/p>\n<p>Hai pensato di salire sui token e sul carrozzone del metaverso? Reda Bouraoui, uno dei nostri stimati investitori che \u00e8 un dirigente di livello C e un ex allievo della Scuola di Business di Harvard, scrive una serie di articoli intellettuali e perspicaci sulla tecnologia blockchain. Ecco un assaggio di uno dei suoi articoli di tendenza su Trasformazione e gioco.<\/p>\n<p>Abituati al concetto di \u201cSOLDI PER TUTTO\u201d. Il nostro futuro viene tokenizzato. Le rivoluzioni tecnologiche non sono nuove. Guarda come Web2 ha svolto un ruolo di trasformazione negli ultimi 20 anni. Ad esempio, ha ucciso il mercato dei CD, ha ucciso anche il mercato degli mp3 e ha portato lo streaming musicale (Apple, Spotify, &#8230;) dove \u00e8 oggi. Allo stesso tempo, ha semplicemente trasformato l&#8217;economia del settore; rimuovendo le royalties degli artisti dalla vendita di CD (che rappresentavano il 90% delle entrate degli artisti musicali) per essere sostituite dalle entrate dello streaming e del merchandising.<\/p>\n<p>Ulteriori informazioni su <a href=\"https:\/\/bit.ly\/3u8IOgI\">https:\/\/bit.ly\/3u8IOgI<\/a><\/p>\n<p><strong>AIX MVP della Stagione 2021\/2022<\/strong><\/p>\n<p>Iago Aspas, giocatore chiave dell&#8217;RC Celta, \u00e8 stato nominato MVP della stagione per la sua straordinaria prestazione nella stagione 2021\/2022. Ha giocato 37 partite e segnato 18 gol durante la stagione. Iago Aspas ha ricevuto il titolo per riconoscere la sua impressionante coerenza e influenza nella Liga.<\/p>\n<p><strong>Partnership Fiorente<\/strong><\/p>\n<p>I membri dell&#8217;RC Celta &#8211; la squadra della Liga Santander &#8211; hanno visitato Dubai dal 23 al 26 Maggio 2022, dopo l&#8217;ennesima stagione straordinaria. Erano presenti giocatori di spicco come Iago Aspas, Fran Beltran, Joseph Aidoo ed i membri ufficiali. In qualit\u00e0 di sponsor ufficiale dell&#8217;RC Celta, lo scopo della visita era rafforzare la nostra partnership, svelare la maglia della nuova stagione e premiare l&#8217;MVP della stagione. I tre giorni ricchi di eventi hanno incluso discussioni sulla strategia futura e sulla crescita della partnership. il Gruppo AIX per gli Investimenti \u00e8 diventato lo sponsor ufficiale di RC Celta all&#8217;inizio dello scorso anno ed \u00e8 orgoglioso del suo impatto sullo sport attraverso questa alleanza strategica.<\/p>\n<p><strong>Una grande stagione per il Fursan Hispania FC<\/strong><\/p>\n<p>Il Fursan Hispania FC \u00e8 emerso come il vincitore della Lega di seconda divisione degli Emirati Arabi Uniti 2021\/2022. Dopo l&#8217;ultima partita contro La Liga HPC, il club \u00e8 stato nominato Campioni di Lega e ha ricevuto un trofeo. Nella prossima stagione che inizier\u00e0 all&#8217;inizio di Settembre, Fursan Hispania garegger\u00e0 nella Lega di prima divisione degli Emirati Arabi Uniti 2022\/2023 e nella Coppa del Presidente degli Emirati Arabi Uniti. In qualit\u00e0 di sponsor principale, il Gruppo AIX per gli Investimenti \u00e8 orgoglioso del successo del club.<\/p>\n<p><strong>I consulenti finanziari avanzano nella loro maestria<\/strong><\/p>\n<p>Aggiungendo un altro accreditamento ai loro portafogli, il team di consulenti finanziari di AIX \u00e8 stato certificato dalla Scuola del Business di Harvard negli Investimenti Alternativi. \u00c8 stato un corso intensivo ed efficace che \u00e8 durato pi\u00f9 di cinque settimane, con test settimanali per esaminare la comprensione dell&#8217;arg omento da parte del team. Al completamento con successo, 54 dipendenti hanno ricevuto un certificato. Questa iniziativa \u00e8 stata presa dal management di AIX, per migliorare la conoscenza del team nell&#8217;evoluzione del mercato e delle tendenze, garantendo il miglior servizio alla clientela dell&#8217;azienda.<\/p>\n<p><em>&#8220;Non conoscerai mai la vera libert\u00e0 finch\u00e9 non raggiungerai la libert\u00e0 <\/em><br \/>\n<em>finanziaria.&#8221;<\/em> &#8211; Robert Kiyosaki<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Messaggio de Presidente del Consiglio &#8220;Abbiamo grandi piani per elevare la crescita del business e abbiamo immaginato un grande futuro, per i nostri clienti e l&#8217;azienda&#8221; Un quarto di risultati positivi Sostenendo l&#8217;ottimo inizio dell&#8217;anno per tutto il secondo trimestre,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":13198,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[98],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIX Group AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Quarto di Risultati Positivi\" \/>\n<meta property=\"og:description\" content=\"Messaggio de Presidente del Consiglio &#8220;Abbiamo grandi piani per elevare la crescita del business e abbiamo immaginato un grande futuro, per i nostri clienti e l&#8217;azienda&#8221; Un quarto di risultati positivi Sostenendo l&#8217;ottimo inizio dell&#8217;anno per tutto il secondo trimestre,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/\" \/>\n<meta property=\"og:site_name\" content=\"AIX Group AG\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-01T07:24:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2022\/06\/images-1200x900.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"aixteam aixteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"aixteam aixteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AIX Group AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Un Quarto di Risultati Positivi","og_description":"Messaggio de Presidente del Consiglio &#8220;Abbiamo grandi piani per elevare la crescita del business e abbiamo immaginato un grande futuro, per i nostri clienti e l&#8217;azienda&#8221; Un quarto di risultati positivi Sostenendo l&#8217;ottimo inizio dell&#8217;anno per tutto il secondo trimestre,...","og_url":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/","og_site_name":"AIX Group AG","article_published_time":"2022-07-01T07:24:18+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2022\/06\/images-1200x900.png","type":"image\/png"}],"author":"aixteam aixteam","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"aixteam aixteam","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#article","isPartOf":{"@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/"},"author":{"name":"aixteam aixteam","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3"},"headline":"Un Quarto di Risultati Positivi","datePublished":"2022-07-01T07:24:18+00:00","dateModified":"2022-07-01T07:24:18+00:00","mainEntityOfPage":{"@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/"},"wordCount":1110,"publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"image":{"@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2022\/06\/images.png","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/","url":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/","name":"Un Quarto di Risultati Positivi | AIX Group AG","isPartOf":{"@id":"https:\/\/aixgroup.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#primaryimage"},"image":{"@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2022\/06\/images.png","datePublished":"2022-07-01T07:24:18+00:00","dateModified":"2022-07-01T07:24:18+00:00","breadcrumb":{"@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#primaryimage","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2022\/06\/images.png","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2022\/06\/images.png","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/aixgroup.ch\/a-quarter-of-successful-deliverables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aixgroup.ch\/"},{"@type":"ListItem","position":2,"name":"Un Quarto di Risultati Positivi"}]},{"@type":"WebSite","@id":"https:\/\/aixgroup.ch\/#website","url":"https:\/\/aixgroup.ch\/","name":"AIX Group AG","description":"Our proven track record allows us to offer investors fixed returns via AIX BOND, while minimizing the risk and helping them invest in a safe way.","publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aixgroup.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/aixgroup.ch\/#organization","name":"AIX Group AG","url":"https:\/\/aixgroup.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","width":549,"height":304,"caption":"AIX Group AG"},"image":{"@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3","name":"aixteam aixteam","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","caption":"aixteam aixteam"},"sameAs":["https:\/\/aixgroup.ch"]}]}},"_links":{"self":[{"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/posts\/13205"}],"collection":[{"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/comments?post=13205"}],"version-history":[{"count":1,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/posts\/13205\/revisions"}],"predecessor-version":[{"id":13212,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/posts\/13205\/revisions\/13212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/media\/13198"}],"wp:attachment":[{"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/media?parent=13205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/categories?post=13205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aixgroup.ch\/it\/wp-json\/wp\/v2\/tags?post=13205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}