{"id":7497,"date":"2020-10-21T07:16:01","date_gmt":"2020-10-21T07:16:01","guid":{"rendered":"https:\/\/aixgroup.ch\/?p=7497"},"modified":"2020-10-21T07:21:55","modified_gmt":"2020-10-21T07:21:55","slug":"work-hard-play-hard","status":"publish","type":"post","link":"https:\/\/aixgroup.ch\/de\/work-hard-play-hard\/","title":{"rendered":"Work hard. Play hard."},"content":{"rendered":"<p>Teambildung ist ein wesentlicher Bestandteil einer erfolgreichen kulturellen Organisation, da sie die Beziehung zwischen Teammitgliedern au\u00dferhalb des Arbeitsbereichs st\u00e4rkt und Anerkennung f\u00fcr eine gut gemachte Arbeit bietet.<\/p>\n<p>Wir bei AIX glauben an Leistung und Anerkennung. Deshalb haben wir k\u00fcrzlich einen Teambuilding-Tag veranstaltet, um Spa\u00df, Freude und Kameradschaft zu bringen.<\/p>\n<p>Und es ist einfach, ein relativ gut geliertes Team zu haben, wenn die Zeiten gut sind, der Umsatz flie\u00dft und die Gewinne jedes Jahr verdreifacht werden &#8211; die Zeiten, in denen Unternehmen das Gef\u00fchl haben, Geld f\u00fcr pers\u00f6nliche, F\u00fchrungs- und Teamentwicklung ausgeben zu k\u00f6nnen. In Rezessionen, herausfordernden Zeiten und Zeiten der Unsicherheit ist dies jedoch die Zeit, in der diese Entwicklung mehr denn je ben\u00f6tigt wird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7481\" src=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-768x1024.jpg\" alt=\"\" width=\"400\" height=\"533\" srcset=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-768x1024.jpg 768w, https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-225x300.jpg 225w, https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-1152x1536.jpg 1152w, https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-1536x2048.jpg 1536w, https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-1200x1600.jpg 1200w, https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-1980x2640.jpg 1980w, https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_8381-scaled.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>Die einfache Tatsache ist, dass unabh\u00e4ngig von den Pr\u00e4mien, die ein einzelner Mitarbeiter erh\u00e4lt, die Qualit\u00e4t und Effektivit\u00e4t eines Teams, das nahtlos zusammenarbeitet, einer der Schl\u00fcsselfaktoren ist, die dazu f\u00fchren, dass ein Unternehmen gro\u00dfe Herausforderungen bew\u00e4ltigt &#8211; oder Erfolg hat. Denn es gibt nur sehr wenige Mitarbeiter in einer Organisation auf der Welt, die in einem Vakuum arbeiten. So viel von dem, was wir tun, h\u00e4ngt ganz und gar von einer gemeinsamen Vision, Zielen und echtem Zuh\u00f6ren, Verst\u00e4ndnis, Unterst\u00fctzung und Engagement, Kameradschaft und Zusammenhalt eines Teams ab, zu dem wir geh\u00f6ren.<\/p>\n<p>Aus diesem Grund setzen Spitzensportteams die F\u00e4higkeiten einer ganzen Gruppe von Trainern, Psychologen und Entwicklungsgurus ein, damit jeder Sportler und sein Team sein volles Potenzial entfalten k\u00f6nnen. Unternehmen m\u00fcssen dieselbe Denkweise und denselben Ressourcenumfang haben.<\/p>\n<p>Jeder hat eine andere DNA und ist durch unterschiedliche Ziele motiviert. Entgegen der allgemeinen Meinung ist Geld nicht der Schl\u00fcsselfaktor f\u00fcr den Austritt der meisten Menschen aus einem Unternehmen.<\/p>\n<p>Echte Teamarbeit, Teamentwicklung und Teamcoaching sind zu wichtig, um sie den einmal im Jahr stattfindenden Teambildung-Tagen zu \u00fcberlassen. Es wird ma\u00dfgeblich \u00fcber den Erfolg oder Misserfolg Ihres Unternehmens entscheiden und nirgendwo wichtiger als in herausfordernden Zeiten. Geben Sie es die Wichtigkeit, die \u201ces\u201d &#8211; und Ihr Team &#8211; verdienen.<\/p>\n<p>Stellen Sie all die guten Dinge in einen Unternehmenskalender. Wenn Sie neben dem unerm\u00fcdlichen Druck von Verkaufszielen, Gewinnzielen und Wachstum keinen Spa\u00df haben k\u00f6nnen, stellt ein Unternehmen seine Mitarbeiter nicht an die erste Stelle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teambildung ist ein wesentlicher Bestandteil einer erfolgreichen kulturellen Organisation, da sie die Beziehung zwischen Teammitgliedern au\u00dferhalb des Arbeitsbereichs st\u00e4rkt und Anerkennung f\u00fcr eine gut gemachte Arbeit bietet. Wir bei AIX glauben an Leistung und Anerkennung. Deshalb haben wir k\u00fcrzlich einen&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7493,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[58],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIX Group AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Work hard. Play hard.\" \/>\n<meta property=\"og:description\" content=\"Teambildung ist ein wesentlicher Bestandteil einer erfolgreichen kulturellen Organisation, da sie die Beziehung zwischen Teammitgliedern au\u00dferhalb des Arbeitsbereichs st\u00e4rkt und Anerkennung f\u00fcr eine gut gemachte Arbeit bietet. Wir bei AIX glauben an Leistung und Anerkennung. Deshalb haben wir k\u00fcrzlich einen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aixgroup.ch\/work-hard-play-hard\/\" \/>\n<meta property=\"og:site_name\" content=\"AIX Group AG\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T07:16:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T07:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_83821-1200x633.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aixteam aixteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"aixteam aixteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AIX Group AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Work hard. Play hard.","og_description":"Teambildung ist ein wesentlicher Bestandteil einer erfolgreichen kulturellen Organisation, da sie die Beziehung zwischen Teammitgliedern au\u00dferhalb des Arbeitsbereichs st\u00e4rkt und Anerkennung f\u00fcr eine gut gemachte Arbeit bietet. Wir bei AIX glauben an Leistung und Anerkennung. Deshalb haben wir k\u00fcrzlich einen...","og_url":"https:\/\/aixgroup.ch\/work-hard-play-hard\/","og_site_name":"AIX Group AG","article_published_time":"2020-10-21T07:16:01+00:00","article_modified_time":"2020-10-21T07:21:55+00:00","og_image":[{"width":1024,"height":540,"url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_83821-1200x633.jpg","type":"image\/jpeg"}],"author":"aixteam aixteam","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"aixteam aixteam","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#article","isPartOf":{"@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/"},"author":{"name":"aixteam aixteam","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3"},"headline":"Work hard. Play hard.","datePublished":"2020-10-21T07:16:01+00:00","dateModified":"2020-10-21T07:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/"},"wordCount":390,"publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"image":{"@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_83821.jpg","articleSection":["Veranstaltungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/","url":"https:\/\/aixgroup.ch\/work-hard-play-hard\/","name":"Work hard. Play hard. | AIX Group AG","isPartOf":{"@id":"https:\/\/aixgroup.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#primaryimage"},"image":{"@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_83821.jpg","datePublished":"2020-10-21T07:16:01+00:00","dateModified":"2020-10-21T07:21:55+00:00","breadcrumb":{"@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aixgroup.ch\/work-hard-play-hard\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#primaryimage","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_83821.jpg","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/10\/IMG_83821.jpg","width":2560,"height":1351},{"@type":"BreadcrumbList","@id":"https:\/\/aixgroup.ch\/work-hard-play-hard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aixgroup.ch\/"},{"@type":"ListItem","position":2,"name":"Work hard. Play hard."}]},{"@type":"WebSite","@id":"https:\/\/aixgroup.ch\/#website","url":"https:\/\/aixgroup.ch\/","name":"AIX Group AG","description":"Our proven track record allows us to offer investors fixed returns via AIX BOND, while minimizing the risk and helping them invest in a safe way.","publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aixgroup.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aixgroup.ch\/#organization","name":"AIX Group AG","url":"https:\/\/aixgroup.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","width":549,"height":304,"caption":"AIX Group AG"},"image":{"@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3","name":"aixteam aixteam","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","caption":"aixteam aixteam"},"sameAs":["https:\/\/aixgroup.ch"]}]}},"_links":{"self":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/7497"}],"collection":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/comments?post=7497"}],"version-history":[{"count":0,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/7497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media\/7493"}],"wp:attachment":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media?parent=7497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/categories?post=7497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/tags?post=7497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}