{"id":6435,"date":"2020-04-09T16:52:31","date_gmt":"2020-04-09T16:52:31","guid":{"rendered":"https:\/\/aixgroup.ch\/with-confidence-to-consistent-results\/"},"modified":"2021-12-29T08:50:49","modified_gmt":"2021-12-29T04:50:49","slug":"with-confidence-to-consistent-results","status":"publish","type":"post","link":"https:\/\/aixgroup.ch\/de\/with-confidence-to-consistent-results\/","title":{"rendered":"Q1 2020: Mit Zuversicht zu konsistenten Ergebnissen"},"content":{"rendered":"<p><strong>CEO\u2019s Leadership Talk<\/strong><\/p>\n<p>Das erste Quartal des Jahres 2020 hat gro\u00dfe Unterschiede zwischen altmodischen Unternehmen und Unternehmen mit einer innovativen &#8220;unkonventionellen&#8221; Denkweise gezeigt.<\/p>\n<p>In der AIX Investment Group glauben wir fest an Wissenschaft und Technologie. Alle unsere Bem\u00fchungen sind darauf ausgerichtet, unseren angesehenen Kunden ausgezeichnete Ergebnisse zu liefern.<\/p>\n<div style=\"height:15px\"><\/div>\n<p><strong>Ausblick auf globale M\u00e4rkte<\/strong><\/p>\n<p>Die Coronavirus-Pandemie wird einen scharfen und tiefen wirtschaftlichen Schock ausl\u00f6sen. Die Marktbewegungen erinnern an die dunkelsten Tage der Finanzkrise im Jahr 2008, aber der volatile Markt ist gleichzeitig eine Gelegenheit f\u00fcr erfahrene H\u00e4ndler, die Marktvolatilit\u00e4t auszunutzen und Gewinne zu erzielen.<\/p>\n<p>Obwohl die Dauer der Viruspandemie nicht vorhersehbar ist, sprechen politische Anreize, Nachholbedarf und das Fehlen gr\u00f6\u00dferer Ungleichgewichte f\u00fcr einen soliden Aufschwung, wenn die Virusbedrohung abklingt.<\/p>\n<p>Dow Jones: \u2013 19.09%<br \/>\nS&amp;P 500: \u2013 12.95%<br \/>\nFTSE: \u2013 25.97%<br \/>\nDAX: \u2013 19.94%<br \/>\nRoh\u00f6lpreis: \u2013 64%<br \/>\nImmobilienindex: \u2013 34%<\/p>\n<p>W\u00e4hrend die internationalen Kapitalm\u00e4rkte im 1. Quartal 2020 mit Schwierigkeiten zu k\u00e4mpfen hatten, hat AIX Investment Group das 1. Quartal 2020 mit beeindruckenden Ergebnissen abgeschlossen.<\/p>\n<p><strong><em>&#8220;Die Risiken, aus dem Spiel zu sein, sind im Vergleich zu den Risiken, im Spiel zu sein, enorm.&#8221;<\/em><\/strong><\/p>\n<p><strong>AIX DYNAMIC<\/strong><\/p>\n<p>AIX DYNAMIC ist ein vollst\u00e4ndig verwaltetes individuelles Handelskonto, das bei er\u00f6ffnet und von der AIX Investment Group verwaltet wird. Unser erfahrenes Team verwendet verschiedene diversifizierte Tradingstrategien und -instrumente, die alle darauf abzielen, das Risiko zu minimieren und den Gewinn zu maximieren. Im ersten Quartal waren wir sehr aktiv im Handel mit W\u00e4hrungspaaren (EUR\/USD, EUR\/GBP, EUR\/JPY, GBP\/USD, GBP\/JPY, USD\/JPY, USD\/CAD), Rohstoff-CFD (XAU\/USD, XAG\/USD) und Krypto-W\u00e4hrungs-CFD (BTC\/USD, ETH\/USD, XRP\/USD).<\/p>\n<p>Januar 2020: +0.4%<br \/>\nFebruar 2020: +1.8%<br \/>\nM\u00e4rz 2020: +2.9%<\/p>\n<p><strong>Q1 2020: +5.1%<\/strong><\/p>\n<p>Wir erwarten Best\u00e4ndigkeit bei unseren k\u00fcnftigen Ergebnissen.<\/p>\n<p><strong>AIX DIGITAL ASSETS<\/strong><\/p>\n<p>Die Finanzm\u00e4rkte ver\u00e4ndern sich rasch. Wir glauben fest an Wissenschaft und Technologie und setzen sie ein, um unseren Investoren zu helfen, ihre finanziellen Ziele zu erreichen. Es gibt mehrere verschiedene digitale Verm\u00f6genswerte, die zum Handeln und\/oder Investieren zur Verf\u00fcgung stehen.<\/p>\n<p>Unser Team von Blockchain-Spezialisten bietet aufschlussreiche Beratung zu Investitionen in Kryptow\u00e4hrungen.<\/p>\n<p><strong>AIX SECURE<\/strong><\/p>\n<p>Anlageprodukt mit festen Auszahlungsterminen und -betr\u00e4gen, hat im 1. Quartal jede einzelne Auszahlung erfolgreich abgeschlossen (+3,6%). Das Portfolio von AIX SECURE ist durch Investitionen in verschiedene Anlageklassen ausgewogen und diversifiziert.<\/p>\n<p>Unternehmen, die in einer wirtschaftlichen Rezession am besten abschneiden, machen zwei Dinge gut. Erstens sind sie vor Beginn der Rezession strategisch gut positioniert, und zweitens reagieren sie effizient und schnell, um ihre Gesch\u00e4ftst\u00e4tigkeit entsprechend dem unterschiedlichen Marktverhalten zu optimieren.<\/p>\n<p>Warren Buffett sagte vor Jahren:<\/p>\n<p><em>&#8220;Versuchen Sie, \u00e4ngstlich zu sein, wenn andere gierig sind, und gierig nur, wenn andere \u00e4ngstlich sind.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CEO\u2019s Leadership Talk Das erste Quartal des Jahres 2020 hat gro\u00dfe Unterschiede zwischen altmodischen Unternehmen und Unternehmen mit einer innovativen &#8220;unkonventionellen&#8221; Denkweise gezeigt. In der AIX Investment Group glauben wir fest an Wissenschaft und Technologie. Alle unsere Bem\u00fchungen sind darauf&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[59],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIX Group AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q1 2020: Mit Zuversicht zu konsistenten Ergebnissen\" \/>\n<meta property=\"og:description\" content=\"CEO\u2019s Leadership Talk Das erste Quartal des Jahres 2020 hat gro\u00dfe Unterschiede zwischen altmodischen Unternehmen und Unternehmen mit einer innovativen &#8220;unkonventionellen&#8221; Denkweise gezeigt. In der AIX Investment Group glauben wir fest an Wissenschaft und Technologie. Alle unsere Bem\u00fchungen sind darauf...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/\" \/>\n<meta property=\"og:site_name\" content=\"AIX Group AG\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T16:52:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T04:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/04\/Trade-Spat-Wipes-Out-1-Trillion-From-Global-Stock-Market-Values-772x485-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"772\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aixmanager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"aixmanager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AIX Group AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Q1 2020: Mit Zuversicht zu konsistenten Ergebnissen","og_description":"CEO\u2019s Leadership Talk Das erste Quartal des Jahres 2020 hat gro\u00dfe Unterschiede zwischen altmodischen Unternehmen und Unternehmen mit einer innovativen &#8220;unkonventionellen&#8221; Denkweise gezeigt. In der AIX Investment Group glauben wir fest an Wissenschaft und Technologie. Alle unsere Bem\u00fchungen sind darauf...","og_url":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/","og_site_name":"AIX Group AG","article_published_time":"2020-04-09T16:52:31+00:00","article_modified_time":"2021-12-29T04:50:49+00:00","og_image":[{"width":772,"height":485,"url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/04\/Trade-Spat-Wipes-Out-1-Trillion-From-Global-Stock-Market-Values-772x485-1.jpg","type":"image\/jpeg"}],"author":"aixmanager","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"aixmanager","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#article","isPartOf":{"@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/"},"author":{"name":"aixmanager","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/3f6d062751f3b3352b3fa882823c1d1a"},"headline":"Q1 2020: Mit Zuversicht zu konsistenten Ergebnissen","datePublished":"2020-04-09T16:52:31+00:00","dateModified":"2021-12-29T04:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/"},"wordCount":435,"publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"image":{"@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/04\/Trade-Spat-Wipes-Out-1-Trillion-From-Global-Stock-Market-Values-772x485-1.jpg","articleSection":["Newsletter"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/","url":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/","name":"Q1 2020: Mit Zuversicht zu konsistenten Ergebnissen | AIX Group AG","isPartOf":{"@id":"https:\/\/aixgroup.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#primaryimage"},"image":{"@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/04\/Trade-Spat-Wipes-Out-1-Trillion-From-Global-Stock-Market-Values-772x485-1.jpg","datePublished":"2020-04-09T16:52:31+00:00","dateModified":"2021-12-29T04:50:49+00:00","breadcrumb":{"@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#primaryimage","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/04\/Trade-Spat-Wipes-Out-1-Trillion-From-Global-Stock-Market-Values-772x485-1.jpg","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2020\/04\/Trade-Spat-Wipes-Out-1-Trillion-From-Global-Stock-Market-Values-772x485-1.jpg","width":772,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/aixgroup.ch\/q1-2020-with-confidence-to-consistent-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aixgroup.ch\/"},{"@type":"ListItem","position":2,"name":"Q1 2020: Mit Zuversicht zu konsistenten Ergebnissen"}]},{"@type":"WebSite","@id":"https:\/\/aixgroup.ch\/#website","url":"https:\/\/aixgroup.ch\/","name":"AIX Group AG","description":"Our proven track record allows us to offer investors fixed returns via AIX BOND, while minimizing the risk and helping them invest in a safe way.","publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aixgroup.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aixgroup.ch\/#organization","name":"AIX Group AG","url":"https:\/\/aixgroup.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","width":549,"height":304,"caption":"AIX Group AG"},"image":{"@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/3f6d062751f3b3352b3fa882823c1d1a","name":"aixmanager","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0aacd8d049137dab3d640a01db95dc2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0aacd8d049137dab3d640a01db95dc2d?s=96&d=mm&r=g","caption":"aixmanager"}}]}},"_links":{"self":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/6435"}],"collection":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/comments?post=6435"}],"version-history":[{"count":1,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/6435\/revisions"}],"predecessor-version":[{"id":11572,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/6435\/revisions\/11572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media\/6436"}],"wp:attachment":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media?parent=6435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/categories?post=6435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/tags?post=6435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}