{"id":15501,"date":"2023-05-05T10:48:20","date_gmt":"2023-05-05T06:48:20","guid":{"rendered":"https:\/\/aixgroup.ch\/?p=15501"},"modified":"2023-06-26T15:13:22","modified_gmt":"2023-06-26T11:13:22","slug":"aix-investment-group-contributes-to-al-jalila-foundations-mission","status":"publish","type":"post","link":"https:\/\/aixgroup.ch\/de\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/","title":{"rendered":"AIX Investment Groups Beitrag zur Mission der Al Jalila Foundation"},"content":{"rendered":"<p>Die AIX Investment Group ist stolz darauf, ihre Spende von 1 Million AED an die Al Jalila Foundation, eine f\u00fchrende Wohlt\u00e4tigkeitsorganisation im Gesundheitswesen der Vereinigten Arabischen Emirate, bekannt zu geben.<\/p>\n<p>Die Spende erfolgte am 14. April 2023 w\u00e4hrend des Heiligen Monats Ramadan am Hauptsitz der Stiftung. Bei der Zeremonie anwesend waren Dr. Amer Al Zarooni, CEO der Al Jalila Foundation, der ehrenwerter AIX Partner Rashid Khalaf Al Habtoors, der AIX-Vorstandsvorsitzende Fadi Dabbagh, die bekannte Fu\u00dfballlegende Michel Salgado sowie andere offizielle Repr\u00e4sentanten.<\/p>\n<p>Die Spende spiegelt das Engagement von AIX wider, medizinische Innovationen zu f\u00f6rdern und die Gesundheitsversorgung in den Vereinigten Arabischen Emiraten zu verbessern.<\/p>\n<p>Die Al Jalila Foundation erm\u00f6glicht medizinische Behandlung f\u00fcr Personen, die sich keine hochwertige Gesundheitsversorgung leisten k\u00f6nnen.<\/p>\n<p>Sie vergibt dar\u00fcber hinaus Stipendien zur F\u00f6rderung einer einheimischen Generation von Medizinern und unterst\u00fctzt erstklassige Forschung, die sich mit den in der Region vorherrschenden Gesundheitsproblemen wie Krebs, Herz-Kreislauf-Erkrankungen, Diabetes und Fettleibigkeit sowie psychischer Gesundheit befasst.<\/p>\n<p>Dr. Amer Al Zarooni, CEO der Al Jalila Foundation, dankte der AIX Investment Group f\u00fcr ihren gro\u00dfz\u00fcgigen Beitrag und erkl\u00e4rte: \u201eAls philanthropische Organisation im Gesundheitswesen sind wir auf die Unterst\u00fctzung von Partnern und Spendern angewiesen, um innovative Programme zur Verbesserung des Lebens von Patienten bereitzustellen. Wir sind AIX Investment sehr dankbar f\u00fcr ihren gro\u00dfz\u00fcgigen Beitrag, der uns dabei helfen wird, unsere Mission fortzusetzen.\u201c<\/p>\n<p>Der Vorstandsvorsitzende von AIX, Fadi Dabbagh, betonte, dass das Unternehmens stolz darauf sei, die Bem\u00fchungen der Al Jalila Foundation zu unterst\u00fctzen, und damit Leben zu verbessern, sowie medizinische Innovationen zu f\u00f6rdern. Er sagte: \u201eUnsere Spende ist eine Geste an Ihre edle Sache, und wir hoffen, dass es bedeutsame Auswirkungen haben wird.\u201c<\/p>\n<p>Rashid Khalaf Al Habtoor, ein strategischer Partner von AIX, \u00e4u\u00dferte sich \u00e4hnlich: \u201eDurch die Unterst\u00fctzung der Al Jalila Foundation investieren wir in die Zukunft medizinischen Innovationen und bieten denjenigen, die sie am dringendsten ben\u00f6tigen, eine bessere Lebensqualit\u00e4t. Ich bin stolz auf die Bem\u00fchungen und Werte von AIX, der Gemeinschaft etwas zur\u00fcckzugeben.&#8221;<\/p>\n<p>Michel Salgado brachte zum Ausdruck, dass er sich geehrt f\u00fchle, mit einem Unternehmen verbunden zu sein, das der weiteren Gesellschaft Priorit\u00e4t einr\u00e4umt. Die Spende der AIX Investment Group an die Al Jalila Foundation sei eine bewundernswerte Geste, die das Ethos der sozialen Verantwortung und Gro\u00dfz\u00fcgigkeit des Unternehmens unterstreiche. AIX trage so aktiv zur Verbesserung der Gesellschaft bei und f\u00f6rdere eine Kultur der Philanthropie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die AIX Investment Group ist stolz darauf, ihre Spende von 1 Million AED an die Al Jalila Foundation, eine f\u00fchrende Wohlt\u00e4tigkeitsorganisation im Gesundheitswesen der Vereinigten Arabischen Emirate, bekannt zu geben. Die Spende erfolgte am 14. April 2023 w\u00e4hrend des Heiligen&#8230;<\/p>\n","protected":false},"author":3,"featured_media":15354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[56,56,56,56],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIX Group AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AIX Investment Groups Beitrag zur Mission der Al Jalila Foundation\" \/>\n<meta property=\"og:description\" content=\"Die AIX Investment Group ist stolz darauf, ihre Spende von 1 Million AED an die Al Jalila Foundation, eine f\u00fchrende Wohlt\u00e4tigkeitsorganisation im Gesundheitswesen der Vereinigten Arabischen Emirate, bekannt zu geben. Die Spende erfolgte am 14. April 2023 w\u00e4hrend des Heiligen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/\" \/>\n<meta property=\"og:site_name\" content=\"AIX Group AG\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T06:48:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:13:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2023\/04\/Aljalila-Foundation-1200x809.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"aixteam aixteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"aixteam aixteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AIX Group AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"AIX Investment Groups Beitrag zur Mission der Al Jalila Foundation","og_description":"Die AIX Investment Group ist stolz darauf, ihre Spende von 1 Million AED an die Al Jalila Foundation, eine f\u00fchrende Wohlt\u00e4tigkeitsorganisation im Gesundheitswesen der Vereinigten Arabischen Emirate, bekannt zu geben. Die Spende erfolgte am 14. April 2023 w\u00e4hrend des Heiligen...","og_url":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/","og_site_name":"AIX Group AG","article_published_time":"2023-05-05T06:48:20+00:00","article_modified_time":"2023-06-26T11:13:22+00:00","og_image":[{"width":2560,"height":1727,"url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2023\/04\/Aljalila-Foundation-1200x809.webp","type":"image\/webp"}],"author":"aixteam aixteam","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"aixteam aixteam","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#article","isPartOf":{"@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/"},"author":{"name":"aixteam aixteam","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3"},"headline":"AIX Investment Groups Beitrag zur Mission der Al Jalila Foundation","datePublished":"2023-05-05T06:48:20+00:00","dateModified":"2023-06-26T11:13:22+00:00","mainEntityOfPage":{"@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/"},"wordCount":424,"publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"image":{"@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2023\/04\/Aljalila-Foundation.webp","articleSection":["Einblick","Einblick","Einblick","Einblick"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/","url":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/","name":"AIX Investment Groups Beitrag zur Mission der Al Jalila Foundation | AIX Group AG","isPartOf":{"@id":"https:\/\/aixgroup.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#primaryimage"},"image":{"@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2023\/04\/Aljalila-Foundation.webp","datePublished":"2023-05-05T06:48:20+00:00","dateModified":"2023-06-26T11:13:22+00:00","breadcrumb":{"@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#primaryimage","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2023\/04\/Aljalila-Foundation.webp","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2023\/04\/Aljalila-Foundation.webp","width":2560,"height":1727},{"@type":"BreadcrumbList","@id":"https:\/\/aixgroup.ch\/aix-investment-group-contributes-to-al-jalila-foundations-mission\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aixgroup.ch\/"},{"@type":"ListItem","position":2,"name":"AIX Investment Groups Beitrag zur Mission der Al Jalila Foundation"}]},{"@type":"WebSite","@id":"https:\/\/aixgroup.ch\/#website","url":"https:\/\/aixgroup.ch\/","name":"AIX Group AG","description":"Our proven track record allows us to offer investors fixed returns via AIX BOND, while minimizing the risk and helping them invest in a safe way.","publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aixgroup.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aixgroup.ch\/#organization","name":"AIX Group AG","url":"https:\/\/aixgroup.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","width":549,"height":304,"caption":"AIX Group AG"},"image":{"@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3","name":"aixteam aixteam","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","caption":"aixteam aixteam"},"sameAs":["https:\/\/aixgroup.ch"]}]}},"_links":{"self":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/15501"}],"collection":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/comments?post=15501"}],"version-history":[{"count":2,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/15501\/revisions"}],"predecessor-version":[{"id":15684,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/15501\/revisions\/15684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media\/15354"}],"wp:attachment":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media?parent=15501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/categories?post=15501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/tags?post=15501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}