{"id":11538,"date":"2021-12-23T15:57:12","date_gmt":"2021-12-23T11:57:12","guid":{"rendered":"https:\/\/aixgroup.ch\/?p=11538"},"modified":"2021-12-23T15:57:12","modified_gmt":"2021-12-23T11:57:12","slug":"die-aix-investment-group-wuenscht-ihnen-frohe-festtage","status":"publish","type":"post","link":"https:\/\/aixgroup.ch\/de\/die-aix-investment-group-wuenscht-ihnen-frohe-festtage\/","title":{"rendered":"Die AIX Investment Group w\u00fcnscht Ihnen frohe Festtage."},"content":{"rendered":"<p>R\u00fcckblickend auf das Jahr war es ein fantastisches Jahr der Errungenschaften und neuen H\u00f6hen. Wir haben uns an beispiellose Ver\u00e4nderungen angepasst und den weiteren Erfolg unseres Unternehmens gesichert. F\u00fcr das Ausma\u00df unserer Leistungen sind wir unseren Kunden und unserem engagierten Team unendlich dankbar.<\/p>\n<p>Wir w\u00fcnschen allen eine frohe Weihnachtszeit und ein erfolgreiches neues Jahr, w\u00e4hrend wir auf eine bessere Zukunft im folgenden Jahr hinarbeiten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00fcckblickend auf das Jahr war es ein fantastisches Jahr der Errungenschaften und neuen H\u00f6hen. Wir haben uns an beispiellose Ver\u00e4nderungen angepasst und den weiteren Erfolg unseres Unternehmens gesichert. F\u00fcr das Ausma\u00df unserer Leistungen sind wir unseren Kunden und unserem engagierten&#8230;<\/p>\n","protected":false},"author":3,"featured_media":11531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[58],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIX Group AG<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die AIX Investment Group w\u00fcnscht Ihnen frohe Festtage.\" \/>\n<meta property=\"og:description\" content=\"R\u00fcckblickend auf das Jahr war es ein fantastisches Jahr der Errungenschaften und neuen H\u00f6hen. Wir haben uns an beispiellose Ver\u00e4nderungen angepasst und den weiteren Erfolg unseres Unternehmens gesichert. F\u00fcr das Ausma\u00df unserer Leistungen sind wir unseren Kunden und unserem engagierten...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/\" \/>\n<meta property=\"og:site_name\" content=\"AIX Group AG\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T11:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aixgroup.ch\/wp-content\/uploads\/2021\/12\/web-banner-top-1200x467.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"997\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aixteam aixteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"aixteam aixteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AIX Group AG","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Die AIX Investment Group w\u00fcnscht Ihnen frohe Festtage.","og_description":"R\u00fcckblickend auf das Jahr war es ein fantastisches Jahr der Errungenschaften und neuen H\u00f6hen. Wir haben uns an beispiellose Ver\u00e4nderungen angepasst und den weiteren Erfolg unseres Unternehmens gesichert. F\u00fcr das Ausma\u00df unserer Leistungen sind wir unseren Kunden und unserem engagierten...","og_url":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/","og_site_name":"AIX Group AG","article_published_time":"2021-12-23T11:57:12+00:00","og_image":[{"width":2560,"height":997,"url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2021\/12\/web-banner-top-1200x467.jpg","type":"image\/jpeg"}],"author":"aixteam aixteam","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"aixteam aixteam","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#article","isPartOf":{"@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/"},"author":{"name":"aixteam aixteam","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3"},"headline":"Die AIX Investment Group w\u00fcnscht Ihnen frohe Festtage.","datePublished":"2021-12-23T11:57:12+00:00","dateModified":"2021-12-23T11:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/"},"wordCount":79,"publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"image":{"@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2021\/12\/web-banner-top.jpg","articleSection":["Veranstaltungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/","url":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/","name":"Die AIX Investment Group w\u00fcnscht Ihnen frohe Festtage. | AIX Group AG","isPartOf":{"@id":"https:\/\/aixgroup.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#primaryimage"},"image":{"@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#primaryimage"},"thumbnailUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2021\/12\/web-banner-top.jpg","datePublished":"2021-12-23T11:57:12+00:00","dateModified":"2021-12-23T11:57:12+00:00","breadcrumb":{"@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#primaryimage","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2021\/12\/web-banner-top.jpg","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2021\/12\/web-banner-top.jpg","width":2560,"height":997},{"@type":"BreadcrumbList","@id":"https:\/\/aixgroup.ch\/holiday-greetings-from-aix-investment-group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aixgroup.ch\/"},{"@type":"ListItem","position":2,"name":"Die AIX Investment Group w\u00fcnscht Ihnen frohe Festtage."}]},{"@type":"WebSite","@id":"https:\/\/aixgroup.ch\/#website","url":"https:\/\/aixgroup.ch\/","name":"AIX Group AG","description":"Our proven track record allows us to offer investors fixed returns via AIX BOND, while minimizing the risk and helping them invest in a safe way.","publisher":{"@id":"https:\/\/aixgroup.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aixgroup.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aixgroup.ch\/#organization","name":"AIX Group AG","url":"https:\/\/aixgroup.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/","url":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","contentUrl":"https:\/\/aixgroup.ch\/wp-content\/uploads\/2024\/05\/aix-group-logo.png","width":549,"height":304,"caption":"AIX Group AG"},"image":{"@id":"https:\/\/aixgroup.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/65365c6f26fac6e3060aab27880555f3","name":"aixteam aixteam","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aixgroup.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f2af136fd902bc54621a0119367dfc0?s=96&d=mm&r=g","caption":"aixteam aixteam"},"sameAs":["https:\/\/aixgroup.ch"]}]}},"_links":{"self":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/11538"}],"collection":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/comments?post=11538"}],"version-history":[{"count":2,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/11538\/revisions"}],"predecessor-version":[{"id":11548,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/posts\/11538\/revisions\/11548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media\/11531"}],"wp:attachment":[{"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/media?parent=11538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/categories?post=11538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aixgroup.ch\/de\/wp-json\/wp\/v2\/tags?post=11538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}